{"id":28295,"date":"2021-04-09T19:44:24","date_gmt":"2021-04-09T19:44:24","guid":{"rendered":"https:\/\/sedaxis.com\/healthcare-new1\/?page_id=28295"},"modified":"2021-05-12T08:42:16","modified_gmt":"2021-05-12T08:42:16","slug":"icu-rehabilitation","status":"publish","type":"page","link":"https:\/\/sedaxis.com\/healthcare\/products\/icu-rehabilitation\/","title":{"rendered":"ICU Rehab Devices"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h5><span style=\"color: #00bcd4;\">ICU Rehab Devices<\/span><\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"small-body\" style=\"text-align: justify;\"><span style=\"color: #000000;\">Early mobilization improves not only the functional outcome of these patients in the long term but also the degree of alertness. Timely exercise therapy shortens the duration of intensive care. The therapist can mobilize the patient effortlessly and flexibly. The trainer can be adjusted quickly and individually to the patient.<\/span><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"preloader\"><div class=\"preloader-spin\"><\/div><\/div> <div class=\"portfolio-preloader-wrapper\"> <div data-per-page=\"8\" data-portfolio-uid=\"461615e\" class=\"portfolio no-padding portfolio-pagination-normal portfolio-style-justified background-style-white title-style-light hover-zooming-blur item-animation-move-up title-on-page columns-2\" data-hover=\"zooming-blur\" > <div class=\"\"> <div class=\"row\" style=\"margin: -21px;\"> <div class=\"portfolio-set clearfix\" data-max-row-height=\"380\"> <div class=\"portfolio-item icu_rehabilitation_devices_home thera-trainer_partner-page col-sm-6 col-xs-12 item-animations-not-inited post-28033 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" style=\"padding: 21px;\" data-default-sort=\"0\" data-sort-date=\"1616952330\"> <div class=\"wrap clearfix\" style=\"border-bottom-color: \"> <div class=\"image post-28033 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <div class=\"image-inner\"> <picture> <source srcset=\"https:\/\/sedaxis.com\/healthcare\/wp-content\/uploads\/2021\/05\/bemo-thegem-portfolio-justified-2x-500.png 1x, https:\/\/sedaxis.com\/healthcare\/wp-content\/uploads\/2021\/05\/bemo.png 2x\" media=\"(max-width: 550px)\" sizes=\"100vw\"> <source srcset=\"https:\/\/sedaxis.com\/healthcare\/wp-content\/uploads\/2021\/05\/bemo-thegem-portfolio-justified-2x.png 1x, https:\/\/sedaxis.com\/healthcare\/wp-content\/uploads\/2021\/05\/bemo.png 2x\" media=\"(max-width: 1920px)\" sizes=\"100vw\"> <img src=\"https:\/\/sedaxis.com\/healthcare\/wp-content\/uploads\/2021\/05\/bemo.png\" width=\"432\" height=\"595\" class=\"attachment-thegem-portfolio-justified\" alt=\"BEMO\" \/> <\/picture> <\/div> <div class=\"overlay\"> <div class=\"overlay-circle\"><\/div> <div class=\"links-wrapper\"> <div class=\"links\"> <div class=\"portfolio-icons\"> <a href=\"https:\/\/sedaxis.com\/healthcare\/partners\/thera-trainer\/bemo\/\" target=\"_self\" class=\"icon outer-link \"><\/a> <a href=\"\/\/www.youtube.com\/embed\/h1SJZ8rWAcE?autoplay=1\" target=\"_self\" class=\"icon youtube \"><\/a> <div class=\"overlay-line\"><\/div> <\/div> <\/div> <\/div> <\/div> <\/div> <div class=\"caption post-28033 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\" > <div class=\"title\" > BEMO <\/div> <div class=\"caption-separator\" ><\/div> <\/div> <\/div> <\/div> <\/div><!-- .portflio-set --> <div class=\"portfolio-item-size-container\"> <div class=\"portfolio-item col-sm-6 col-xs-12 item-animations-not-inited post-28033 thegem_pf_item type-thegem_pf_item status-publish has-post-thumbnail\"> <\/div> <\/div> <\/div><!-- .row--> <div class=\"portfolio-navigator gem-pagination\"> <\/div> <\/div><!-- .full-width --> <\/div><!-- .portfolio--> <\/div><!-- .portfolio-preloader-wrapper-->[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] ICU Rehab Devices [\/vc_column_text][vc_column_text] Early mobilization improves not only the functional outcome of these patients in the long term&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":27652,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/pages\/28295"}],"collection":[{"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/comments?post=28295"}],"version-history":[{"count":9,"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/pages\/28295\/revisions"}],"predecessor-version":[{"id":28858,"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/pages\/28295\/revisions\/28858"}],"up":[{"embeddable":true,"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/pages\/27652"}],"wp:attachment":[{"href":"https:\/\/sedaxis.com\/healthcare\/wp-json\/wp\/v2\/media?parent=28295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}